{"id":5375594,"date":"2026-02-26T00:38:49","date_gmt":"2026-02-25T22:38:49","guid":{"rendered":""},"modified":"2026-04-14T03:10:43","modified_gmt":"2026-04-14T01:10:43","slug":"candela-3d-unicorno-24x155x25cm-bunnys-931842","status":"publish","type":"product","link":"https:\/\/gadgettravellers.eu\/it\/shop\/candela-3d-unicorno-24x155x25cm-bunnys-931842\/","title":{"rendered":"Candela 3d Unicorno 24&#215;15,5&#215;2,5cm Bunny&#8217;s 931842"},"content":{"rendered":"<p>Candela 3D a forma di unicorno (Bunny&#8217;s 931842) con dimensioni 24&#215;15,5&#215;2,5 cm, progettata per uso decorativo in camere per bambini, feste a tema o come regalo originale. Ideale per decorare tavoli o scaffali, offre interesse visivo senza richiedere informazioni tecniche per l&#8217;uso. La breve descrizione e le dimensioni facilitano la scelta durante l&#8217;acquisto.<\/p>\n<div class='aiseo-faq-section' style='margin-top:30px; border-top:1px solid #eee; padding-top:20px;'>\n<h3>Domande Frequenti<\/h3>\n<details style='margin-bottom:10px; padding:10px; background:#f9f9f9; border-radius:5px;'>\n<summary style='font-weight:bold; cursor:pointer;'>Quali sono le dimensioni del prodotto?<\/summary>\n<div style='margin-top:10px; color:#555;'>24&#215;15,5&#215;2,5 cm come indicato nella descrizione.<\/div>\n<\/details>\n<details style='margin-bottom:10px; padding:10px; background:#f9f9f9; border-radius:5px;'>\n<summary style='font-weight:bold; cursor:pointer;'>Che tipo di prodotto \u00e8 questo?<\/summary>\n<div style='margin-top:10px; color:#555;'>\u00c8 una candela 3D a forma di unicorno (Bunny&#8217;s 931842), adatta per la decorazione.<\/div>\n<\/details>\n<details style='margin-bottom:10px; padding:10px; background:#f9f9f9; border-radius:5px;'>\n<summary style='font-weight:bold; cursor:pointer;'>Viene menzionato il materiale o il tempo di combustione nella descrizione?<\/summary>\n<div style='margin-top:10px; color:#555;'>La descrizione non menziona il materiale di costruzione n\u00e9 il tempo di combustione.<\/div>\n<\/details>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Candela 3D a forma di unicorno con dimensioni 24&#215;15,5&#215;2,5 cm, adatta per la decorazione di camere per bambini e feste a tema.<\/p>\n","protected":false},"featured_media":20512,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[205054,248634,248635,203676,248001,197261],"product_tag":[247693,172396],"class_list":{"0":"post-5375594","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-candele-decorative","7":"product_cat-candele-pasquali","8":"product_cat-candele-semplici-candele-candelabri","9":"product_cat-decorazioni-per-bambini","10":"product_cat-pasquali","11":"product_cat-regali-per-bambini","12":"product_tag-24x15-5x2-5-cm","13":"product_tag-3d","15":"first","16":"onbackorder","17":"purchasable","18":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/product\/5375594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/comments?post=5375594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/media\/20512"}],"wp:attachment":[{"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/media?parent=5375594"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/product_brand?post=5375594"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/product_cat?post=5375594"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gadgettravellers.eu\/it\/wp-json\/wp\/v2\/product_tag?post=5375594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}